{"id":20403,"date":"2026-05-13T07:27:07","date_gmt":"2026-05-13T07:27:07","guid":{"rendered":"https:\/\/cms.icacordoba.23sd.es\/index.php\/20403\/"},"modified":"2026-05-13T07:35:27","modified_gmt":"2026-05-13T07:35:27","slug":"noticia-la-otra-cara-de-las-plataformas-de-servicios-legales","status":"publish","type":"post","link":"https:\/\/cms.icacordoba.23sd.es\/index.php\/20403\/","title":{"rendered":"NOTICIA \u00bb La otra cara de las plataformas de servicios legales"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"20403\" class=\"elementor elementor-20403\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5040c3d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5040c3d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-33611ea\" data-id=\"33611ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa97f46 elementor-widget elementor-widget-heading\" data-id=\"fa97f46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Informaci\u00f3n CGAE<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb5f531 elementor-widget elementor-widget-text-editor\" data-id=\"cb5f531\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>13-5-2026<\/strong>. \u00bfHas visto alguna vez en internet mensajes como \u201ccancela tus deudas con la segunda oportunidad y elimina el 100 % de ellas\u201d? \u00bfO el eslogan \u201cresolvemos reclamaciones bancarias con resultados garantizados?\u201d \u00bfO incluso ofertas como \u201cevitamos tu desahucio\u201d o \u201cte divorciamos en 48 horas\u201d?<\/p>\n<p>Detr\u00e1s de estos mensajes, cada vez m\u00e1s frecuentes en internet y en redes sociales, puede esconderse algo m\u00e1s que simple publicidad agresiva: posibles fraudes, pr\u00e1cticas enga\u00f1osas o incluso intrusismo profesional. En los \u00faltimos a\u00f1os, se ha producido una proliferaci\u00f3n de plataformas dedicadas a captar clientes en materia de segunda oportunidad. Este crecimiento, en s\u00ed mismo, no es negativo, ya que ha contribuido a que muchos ciudadanos conozcan un mecanismo legal que hasta hace poco era desconocido. Sin embargo, el problema surge cuando algunas de estas empresas traspasan los l\u00edmites de la legalidad y la \u00e9tica profesional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e5b4a49\" data-id=\"e5b4a49\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-209a0ca elementor-widget elementor-widget-video\" data-id=\"209a0ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=TGDKVQDU_f8&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cea119d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"cea119d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bef9d39\" data-id=\"bef9d39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c2cb93 elementor-widget elementor-widget-text-editor\" data-id=\"6c2cb93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 1rem;\">Los miembros del Grupo de trabajo para la protecci\u00f3n profesional de la abogac\u00eda frente a plataformas digitales del Consejo General de la Abogac\u00eda Espa\u00f1ola advierten de que muchas de estas plataformas \u2014algunas con presencia en todo el territorio nacional\u2014, utilizan datos falsos, legislaci\u00f3n derogada o promesas imposibles de cumplir. A ello se suman honorarios poco transparentes o desproporcionados que \u201cdenigran la profesi\u00f3n de la abogac\u00eda\u201d.<\/span><\/p><p>Desde el Grupo se advierte de que \u201chan detectado actuaciones desleales que se aprovechan de las personas m\u00e1s vulnerables, especialmente aquellas endeudadas que buscan acogerse a la segunda oportunidad\u201d, afirman. Frente a ello, recuerdan acudir siempre a un abogado, ya que \u201cel ejercicio de la abogac\u00eda est\u00e1 sujeto a garant\u00edas como la formaci\u00f3n continua, la responsabilidad profesional y el cumplimiento de un estricto c\u00f3digo deontol\u00f3gico\u201d.<\/p><p>La situaci\u00f3n ha encendido las alarmas. Abogados denuncian pr\u00e1cticas como la captaci\u00f3n de clientes mediante falsedades o la oferta de servicios con condiciones poco claras. En los casos m\u00e1s graves, se habla abiertamente de fraude: estafas, cobros indebidos o suplantaci\u00f3n de identidad.<\/p><p>Uno de los focos de preocupaci\u00f3n es el intrusismo profesional. En muchos casos, quienes ofrecen estos servicios no son abogados colegiados, sino \u201casesores\u201d que operan m\u00e1s all\u00e1 de lo permitido por la ley. Si evitan reuniones presenciales, no atienden llamadas, no facilitan copia de documentos o presionan para realizar pagos urgentes, son se\u00f1ales claras de alerta.<\/p><p>El problema no se limita \u00fanicamente a la segunda oportunidad. Desde la Abogac\u00eda Espa\u00f1ola tambi\u00e9n advierten sobre plataformas que act\u00faan en asuntos de vivienda \u2014dirigidos a afectados por desahucios, a quienes prometen err\u00f3neamente solucionar toda su situaci\u00f3n\u2014, o en divorcios, captando clientes con mensajes de \u201cdivorcio expr\u00e9s\u201d y falsas garant\u00edas de rapidez o \u00e9xito.<\/p><p>Para evitar caer en este tipo de enga\u00f1os, los expertos recomiendan verificar siempre si el profesional est\u00e1 colegiado. Una herramienta \u00fatil es el censo oficial disponible en la web de la Abogac\u00eda Espa\u00f1ola. \u201cSi no figura ah\u00ed, desconf\u00ede\u201d, advierten desde la Subcomisi\u00f3n.<\/p><p>El uso del miedo como herramienta publicitaria es otra pr\u00e1ctica habitual. Mensajes alarmistas que apelan a la urgencia o a la desesperaci\u00f3n econ\u00f3mica buscan captar a personas en situaci\u00f3n de vulnerabilidad. Sin embargo, en un entorno publicitario responsable, la promoci\u00f3n de servicios deber\u00eda centrarse en ofrecer informaci\u00f3n objetiva y veraz, sin recurrir a la manipulaci\u00f3n emocional.<\/p><p>Este fen\u00f3meno se agrava en un contexto en el que los ciudadanos contratan servicios sin leer, o sin comprender, las condiciones. Se estima que una persona podr\u00eda tardar m\u00e1s de tres horas en leer los t\u00e9rminos contractuales de una simple web de alquiler vacacional. En ese escenario, no es extra\u00f1o que se pasen por alto cl\u00e1usulas abusivas que, en muchos casos, pueden ser impugnadas judicialmente y declaradas nulas.<\/p><p>Las \u201ctrampas\u201d de internet no solo afectan al bolsillo, sino tambi\u00e9n a derechos fundamentales. El uso de algoritmos para perfilar a los usuarios, la exposici\u00f3n a ciberataques o el acceso indebido a datos personales son riesgos reales en un entorno digital cada vez m\u00e1s complejo.<\/p><p>Como se\u00f1ala Jes\u00fas Pell\u00f3n, miembro del Grupo, el C\u00f3digo Deontol\u00f3gico de la Abogac\u00eda Espa\u00f1ola establece, entre otras cosas, que la relaci\u00f3n entre abogado y cliente debe basarse en la confianza, sin aprovecharse de situaciones de especial vulnerabilidad. Tambi\u00e9n proh\u00edbe pr\u00e1cticas como utilizar a los clientes con fines publicitarios o prometer resultados que no pueden garantizarse. \u201cNo toda deuda puede ser exonerada\u201d, subraya.<\/p><p>\u201cNunca he dicho a un cliente este caso lo vamos a ganar seguro. Garantizar el resultado no es una buena pr\u00e1ctica profesional\u201d, advierte Pell\u00f3n.<\/p><p>En definitiva, el auge de estos servicios pone de manifiesto la necesidad de reforzar la informaci\u00f3n y la protecci\u00f3n del cliente. Porque, en un entorno donde las soluciones r\u00e1pidas y los mensajes atractivos abundan, la prudencia sigue siendo la mejor defensa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n CGAE 13-5-2026. \u00bfHas visto alguna vez en internet mensajes como \u201ccancela tus deudas con la segunda oportunidad y elimina el 100 % de ellas\u201d? \u00bfO el eslogan \u201cresolvemos reclamaciones bancarias con resultados garantizados?\u201d \u00bfO incluso ofertas como \u201cevitamos tu desahucio\u201d o \u201cte divorciamos en 48 horas\u201d? Detr\u00e1s de estos mensajes, cada vez m\u00e1s frecuentes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-20403","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/posts\/20403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/comments?post=20403"}],"version-history":[{"count":6,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/posts\/20403\/revisions"}],"predecessor-version":[{"id":20409,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/posts\/20403\/revisions\/20409"}],"wp:attachment":[{"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/media?parent=20403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/categories?post=20403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/tags?post=20403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}