{"id":14591,"date":"2025-01-28T11:20:06","date_gmt":"2025-01-28T11:20:06","guid":{"rendered":"https:\/\/cms.icacordoba.23sd.es\/index.php\/14591\/"},"modified":"2025-01-28T12:12:22","modified_gmt":"2025-01-28T12:12:22","slug":"noticia-lo-1-2025-los-masc-como-requisito-de-procedibilidad-efectos-procesales-y-relacion-con-las-costas","status":"publish","type":"post","link":"https:\/\/cms.icacordoba.23sd.es\/index.php\/14591\/","title":{"rendered":"NOTICIA \u00bb LO 1\/2025: Los MASC como requisito de procedibilidad. Efectos procesales y relaci\u00f3n con las costas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"14591\" class=\"elementor elementor-14591\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d21ba84 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d21ba84\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-bb9e7ca\" data-id=\"bb9e7ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a90781 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2a90781\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La <\/span>Ley Org\u00e1nica 1\/2025<span style=\"font-weight: 400;\"> se presenta como una actualizaci\u00f3n integral de la normativa sobre mediaci\u00f3n en Espa\u00f1a. Su principal objetivo es<\/span> <span style=\"font-weight: 400;\">introducir en el ordenamiento jur\u00eddico como acceso v\u00e1lido a la Justicia, adem\u00e1s de la jurisdicci\u00f3n,\u00a0<\/span>otros medios adecuados de soluci\u00f3n de controversias en v\u00eda no jurisdiccional (MASC),<span style=\"font-weight: 400;\">\u00a0como medida para la consolidaci\u00f3n de un servicio p\u00fablico de Justicia sostenible, potenciando la negociaci\u00f3n entre las partes, directamente o con la ayuda de un tercero neutral.<\/span><\/p><p><span style=\"font-weight: 400;\">En este contexto, la Comisi\u00f3n de Formaci\u00f3n organiza esta primera sesi\u00f3n de las Jornadas sobre la Ley Org\u00e1nica 1\/2025, con el t\u00edtulo \u201cLos MASC como requisito de procedibilidad tras la reforma <\/span>operada por la nueva Ley 1\/2025. Efectos procesales y relaci\u00f3n con las costas\u201d.<\/p><p>Intervendr\u00e1 <strong>D\u00f1a. Rosal\u00eda Mercedes Fern\u00e1ndez Alaya<\/strong>, Magistrada de la AP de las Palmas y Vicepresidenta de Relaciones Internacionales de GEMME Espa\u00f1a.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d23714b elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d23714b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0c23854 elementor-widget elementor-widget-heading\" data-id=\"0c23854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">INSCRIPCI\u00d3N<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f69d86 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3f69d86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A esta jornada se podr\u00e1 asistir tanto en modalidad presencial como online, previa inscripci\u00f3n.<\/p><p><strong>COSTE DE LA INSCRIPCI\u00d3N:<\/strong><\/p><ul><li>COLEGIADOS ICA-C\u00d3RDOBA: GRATUITO<\/li><li>OTROS PROFESIONALES: 10 \u20ac<\/li><\/ul><div>\u00a0<\/div><div>Puede realizar la inscripci\u00f3n a trav\u00e9s del formulario online.\u00a0<\/div><div>Si no es colegiado, una vez cumplimentado el formulario, deber\u00e1 realizar el ingreso en el n\u00famero de cuenta Banco Santander: ES06 0030 4001 99 0003627271.<\/div><div>Para que la inscripci\u00f3n quede formalizada ser\u00e1 necesario remitir al correo <a href=\"mailto:contabilidad@icacordoba.es\" target=\"_blank\" rel=\"noopener\">contabilidad@icacordoba.es<\/a> el justificante del ingreso bancario.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e01e66 elementor-widget__width-initial elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0e01e66\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef9cd01 elementor-button-info elementor-align-left elementor-widget__width-initial elementor-widget elementor-widget-button\" data-id=\"ef9cd01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/forms.office.com\/e\/DYXY3zVmpW\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INSCRIPCI\u00d3N AQU\u00cd<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-aa071ba\" data-id=\"aa071ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a00d41 elementor-widget elementor-widget-image\" data-id=\"7a00d41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/forms.office.com\/e\/DYXY3zVmpW\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"671\" src=\"https:\/\/cms.icacordoba.23sd.es\/wp-content\/uploads\/2025\/01\/Jornadas-LO-1-2025_Sesion-1-_-Mediacion.jpg\" class=\"attachment-large size-large wp-image-14592\" alt=\"\" srcset=\"https:\/\/cms.icacordoba.23sd.es\/wp-content\/uploads\/2025\/01\/Jornadas-LO-1-2025_Sesion-1-_-Mediacion.jpg 940w, https:\/\/cms.icacordoba.23sd.es\/wp-content\/uploads\/2025\/01\/Jornadas-LO-1-2025_Sesion-1-_-Mediacion-300x251.jpg 300w, https:\/\/cms.icacordoba.23sd.es\/wp-content\/uploads\/2025\/01\/Jornadas-LO-1-2025_Sesion-1-_-Mediacion-768x644.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5837798 elementor-button-info elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5837798\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/forms.office.com\/e\/DYXY3zVmpW\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">INSCRIPCI\u00d3N AQU\u00cd<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Ley Org\u00e1nica 1\/2025 se presenta como una actualizaci\u00f3n integral de la normativa sobre mediaci\u00f3n en Espa\u00f1a. Su principal objetivo es introducir en el ordenamiento jur\u00eddico como acceso v\u00e1lido a la Justicia, adem\u00e1s de la jurisdicci\u00f3n,\u00a0otros medios adecuados de soluci\u00f3n de controversias en v\u00eda no jurisdiccional (MASC),\u00a0como medida para la consolidaci\u00f3n de un servicio p\u00fablico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14591","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/posts\/14591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/comments?post=14591"}],"version-history":[{"count":36,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/posts\/14591\/revisions"}],"predecessor-version":[{"id":14629,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/posts\/14591\/revisions\/14629"}],"wp:attachment":[{"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/media?parent=14591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/categories?post=14591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cms.icacordoba.23sd.es\/index.php\/wp-json\/wp\/v2\/tags?post=14591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}